{"id":1939,"count":1,"description":"","link":"https:\/\/www.loraleelewis.com\/blog\/tag\/stay-in\/","name":"stay in","slug":"stay-in","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.loraleelewis.com\/blog\/wp-json\/wp\/v2\/tags\/1939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loraleelewis.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.loraleelewis.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.loraleelewis.com\/blog\/wp-json\/wp\/v2\/posts?tags=1939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}